{"id":1829,"date":"2015-10-07T01:38:11","date_gmt":"2015-10-07T04:38:11","guid":{"rendered":"http:\/\/nidiasdesign.com\/Photoshoptrucostipsytutoriales\/?p=1829"},"modified":"2017-06-19T19:25:24","modified_gmt":"2017-06-20T00:25:24","slug":"como-hacer-una-pagina-web-personal-tarjeta-de-visitanegociospresentacioncv-sin-codigo","status":"publish","type":"post","link":"https:\/\/nidiasdesign.com\/Photoshoptrucostipsytutoriales\/2015\/10\/07\/como-hacer-una-pagina-web-personal-tarjeta-de-visitanegociospresentacioncv-sin-codigo\/","title":{"rendered":"-> C\u00f3mo hacer una p\u00e1gina web personal, tarjeta de visita\/negocios\/presentaci\u00f3n\/CV Sin C\u00f3digo"},"content":{"rendered":"<p>&nbsp;<\/p>\n<div style=\"text-align:center;\">\n<h1> #Digitarjeta:<br \/>\nBusiness Card Electr\u00f3nica GRATIS<\/h1>\n<\/div>\n<p>&nbsp;<\/p>\n<p>Ya no es una moda, sino una necesidad el tener tu VCard on line. Las tarjetas de presentaci\u00f3n impresas en papel est\u00e1n obsoletas. Hoy en d\u00eda un profesional a la vanguardia tiene su tarjeta de visita o negocios electr\u00f3nica. De manera que si alguien te pide tu Business Card le mandas tu link por mensaje a su celular y puede verla ah\u00ed mismo (responsiva) en su iPone, Tablet,\u00a0Smartphone, etc.<\/p>\n<div style=\"text-align:center;\">\n<script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script><br \/>\n<!-- Intermedioderecho2013 --><br \/>\n<ins class=\"adsbygoogle\"\n     style=\"display:inline-block;width:300px;height:250px\"\n     data-ad-client=\"ca-pub-5090845589511040\"\n     data-ad-slot=\"9590332811\"><\/ins><br \/>\n<script>\n(adsbygoogle = window.adsbygoogle || []).push({});\n<\/script>\n<\/div>\n<p>&nbsp;<\/p>\n<p>De esta forma no corres el riesgo que tiren tu tarjeta de presentaci\u00f3n impresa, sino que aseguras que la tengan siempre presente, actualizada y tu branding personal se refirmar\u00e1 como un profesional elegante y con estilo. No necesitas grandes sumas de dinero para esto, aqu\u00ed te traemos una plantilla web de sitio web personal o CV electr\u00f3nico ( ni mencionar la buena imagen que dejas en los reclutadores de talento en Recursos Humanos de las empresas).<\/p>\n<div style=\"text-align:center;\">\n<script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script><br \/>\n<!-- PDS intermedio 250 AG2013 --><br \/>\n<ins class=\"adsbygoogle\"\n     style=\"display:inline-block;width:300px;height:250px\"\n     data-ad-client=\"ca-pub-5090845589511040\"\n     data-ad-slot=\"7342064410\"><\/ins><br \/>\n<script>\n(adsbygoogle = window.adsbygoogle || []).push({});\n<\/script>\n<\/div>\n<p>&nbsp;<\/p>\n<p>Desc\u00e1rgala ya! y si quieres ver como se edita si c\u00f3digo \u00a1Tambi\u00e9n te dejamos el v\u00eddeo tutorial!<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-1831 size-full\" title=\"C\u00f3mo hacer una p\u00e1gina web personal sin c\u00f3digo HTML4 CSS Responsiva\" src=\"http:\/\/nidiasdesign.com\/Photoshoptrucostipsytutoriales\/wp-content\/uploads\/2015\/10\/Como-crear-una-pagina-web-personal-o-business-Card.jpg\" alt=\"C\u00f3mo crear una p\u00e1gina web personal sin c\u00f3digo HTML4 CSS Responsiva\" width=\"450\" height=\"450\" srcset=\"https:\/\/nidiasdesign.com\/Photoshoptrucostipsytutoriales\/wp-content\/uploads\/2015\/10\/Como-crear-una-pagina-web-personal-o-business-Card.jpg 450w, https:\/\/nidiasdesign.com\/Photoshoptrucostipsytutoriales\/wp-content\/uploads\/2015\/10\/Como-crear-una-pagina-web-personal-o-business-Card-150x150.jpg 150w, https:\/\/nidiasdesign.com\/Photoshoptrucostipsytutoriales\/wp-content\/uploads\/2015\/10\/Como-crear-una-pagina-web-personal-o-business-Card-300x300.jpg 300w, https:\/\/nidiasdesign.com\/Photoshoptrucostipsytutoriales\/wp-content\/uploads\/2015\/10\/Como-crear-una-pagina-web-personal-o-business-Card-144x144.jpg 144w\" sizes=\"(max-width: 450px) 100vw, 450px\" \/><\/p>\n<p>&nbsp;<br \/>\n Si creaste tu business card, te presto mi hosting para subir tu vcard GRATIS, m\u00e1ndame un mail a <strong> nidia@nidiaSdesign.com <\/strong>.<\/p>\n<p><a title=\"Si creaste tu business card, te presto mi hosting para subir tu vcard GRATIS, m\u00e1ndame un mail a nidia@nidiaSdesign.com Y si quieres que yo la modifique por ti, puedo hacerlo por un solo pago de 9.99 d\u00f3lares y lo subo GRATIS a mi hosting para que puedas compartirlo con tus contactos\" href=\"http:\/\/www.templatemo.com\/live\/templatemo_467_easy_profile\" target=\"_blank\"><strong>Download<\/strong>\u00a0Easy profile | VCard | Business Card | Tarjeta de Visita | Tarjeta de presentaci\u00f3n | HTML5 CSS Bootstrap v3.3.5<\/a><\/p>\n<p>Y si quieres que yo la modifique por ti, puedo hacerlo por un solo pago de 9.99 d\u00f3lares y lo subo GRATIS a mi hosting para que puedas compartirlo con tus contactos:<\/p>\n<p>&nbsp;<br \/>\n&nbsp;<\/p>\n<div style=\"text-align:center;\">\n<h1 style=\"text-align: center;\"> Tutorial en v\u00eddeo, paso a paso, para editar la p\u00e1gina web sin c\u00f3digo, con Dreamweaver de Adobe: <\/h1>\n<p>&nbsp;<\/p>\n<h2>** Si creaste tu business card, te presto mi hosting para subir tu vcard GRATIS, m\u00e1ndame un mail a nidia@nidiaSdesign.com . Y si quieres que yo la modifique por ti, puedo hacerlo por un solo pago de 9.99 d\u00f3lares y lo subo GRATIS a mi hosting para que puedas compartirlo con tus contactos: **<\/h2>\n<p>&nbsp;<br \/>\n&nbsp;<br \/>\n<iframe loading=\"lazy\" width=\"420\" height=\"315\" src=\"https:\/\/www.youtube.com\/embed\/9uoVaH7FSLg?rel=0\" frameborder=\"0\" allowfullscreen><\/iframe>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; #Digitarjeta: Business Card Electr\u00f3nica GRATIS &nbsp; Ya no es una moda, sino una necesidad el tener tu VCard on line. Las tarjetas de presentaci\u00f3n impresas en papel est\u00e1n obsoletas. Hoy en d\u00eda un profesional a la vanguardia tiene su tarjeta de visita o negocios electr\u00f3nica. De manera que si alguien te pide tu Business&hellip; <\/p>\n<p class=\"toivo-read-more\"><a href=\"https:\/\/nidiasdesign.com\/Photoshoptrucostipsytutoriales\/2015\/10\/07\/como-hacer-una-pagina-web-personal-tarjeta-de-visitanegociospresentacioncv-sin-codigo\/\" class=\"more-link\">Leer m\u00e1s <span class=\"screen-reader-text\">-> C\u00f3mo hacer una p\u00e1gina web personal, tarjeta de visita\/negocios\/presentaci\u00f3n\/CV Sin C\u00f3digo<\/span><\/a><\/p>\n","protected":false},"author":2,"featured_media":1831,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_mo_disable_npp":"","footnotes":""},"categories":[844,872,839,898,843,840,841,871,842,870],"tags":[858,868,860,869,887,889,2930,2931,895,896,897,846,851,850,878,883,862,9,899,866,867,865,890,856,893,848,852,849,857,879,845,888,861,880,884,886,847,885,882,859,864,853,855,877,875,876,874,892,881,891,873,854,764,894,450,863],"_links":{"self":[{"href":"https:\/\/nidiasdesign.com\/Photoshoptrucostipsytutoriales\/wp-json\/wp\/v2\/posts\/1829"}],"collection":[{"href":"https:\/\/nidiasdesign.com\/Photoshoptrucostipsytutoriales\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nidiasdesign.com\/Photoshoptrucostipsytutoriales\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nidiasdesign.com\/Photoshoptrucostipsytutoriales\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/nidiasdesign.com\/Photoshoptrucostipsytutoriales\/wp-json\/wp\/v2\/comments?post=1829"}],"version-history":[{"count":13,"href":"https:\/\/nidiasdesign.com\/Photoshoptrucostipsytutoriales\/wp-json\/wp\/v2\/posts\/1829\/revisions"}],"predecessor-version":[{"id":2466,"href":"https:\/\/nidiasdesign.com\/Photoshoptrucostipsytutoriales\/wp-json\/wp\/v2\/posts\/1829\/revisions\/2466"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nidiasdesign.com\/Photoshoptrucostipsytutoriales\/wp-json\/wp\/v2\/media\/1831"}],"wp:attachment":[{"href":"https:\/\/nidiasdesign.com\/Photoshoptrucostipsytutoriales\/wp-json\/wp\/v2\/media?parent=1829"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nidiasdesign.com\/Photoshoptrucostipsytutoriales\/wp-json\/wp\/v2\/categories?post=1829"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nidiasdesign.com\/Photoshoptrucostipsytutoriales\/wp-json\/wp\/v2\/tags?post=1829"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}